{"id":105,"count":1,"description":"","link":"https:\/\/henrietteweber.com\/index.php\/tag\/triggers\/","name":"triggers","slug":"triggers","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/henrietteweber.com\/index.php\/wp-json\/wp\/v2\/tags\/105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/henrietteweber.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/henrietteweber.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/henrietteweber.com\/index.php\/wp-json\/wp\/v2\/posts?tags=105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}